{"id":2206,"date":"2025-02-18T13:08:55","date_gmt":"2025-02-18T13:08:55","guid":{"rendered":"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent.webp"},"modified":"2025-02-18T13:09:40","modified_gmt":"2025-02-18T13:09:40","slug":"seo-search-intent-2","status":"inherit","type":"attachment","link":"https:\/\/www.freelance.ro\/blog\/seo-search-intent-2\/","title":{"rendered":"seo-Search-intent"},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-2206","attachment","type-attachment","status-inherit","hentry","excerpt"],"aioseo_notices":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent.webp'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-300x150.webp\" class=\"attachment-medium size-medium\" alt=\"Different types of search intents\" srcset=\"https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-300x150.webp 300w, https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-1024x512.webp 1024w, https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-768x384.webp 768w, https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-1536x768.webp 1536w, https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-2048x1024.webp 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Different types of search intents<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/www.freelance.ro\/blog\/seo-search-intent-2\/\">Citeste mai mult<span class=\"screen-reader-text\">seo-Search-intent<\/span><\/a><\/div>\n"},"alt_text":"Different types of search intents","media_type":"image","mime_type":"image\/webp","media_details":{"width":2400,"height":1200,"file":"2025\/02\/seo-Search-intent.webp","filesize":69224,"sizes":{"medium":{"file":"seo-Search-intent-300x150.webp","width":300,"height":150,"filesize":5174,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-300x150.webp"},"large":{"file":"seo-Search-intent-1024x512.webp","width":1024,"height":512,"filesize":25168,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-1024x512.webp"},"thumbnail":{"file":"seo-Search-intent-900x500.webp","width":900,"height":500,"filesize":24050,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-900x500.webp"},"medium_large":{"file":"seo-Search-intent-768x384.webp","width":768,"height":384,"filesize":18042,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-768x384.webp"},"1536x1536":{"file":"seo-Search-intent-1536x768.webp","width":1536,"height":768,"filesize":40264,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-1536x768.webp"},"2048x2048":{"file":"seo-Search-intent-2048x1024.webp","width":2048,"height":1024,"filesize":55950,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-2048x1024.webp"},"profile_24":{"file":"seo-Search-intent-24x24.webp","width":24,"height":24,"filesize":330,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-24x24.webp"},"profile_48":{"file":"seo-Search-intent-48x48.webp","width":48,"height":48,"filesize":736,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-48x48.webp"},"profile_96":{"file":"seo-Search-intent-96x96.webp","width":96,"height":96,"filesize":1918,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-96x96.webp"},"profile_150":{"file":"seo-Search-intent-150x150.webp","width":150,"height":150,"filesize":3730,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-150x150.webp"},"profile_300":{"file":"seo-Search-intent-300x300.webp","width":300,"height":300,"filesize":9562,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent-300x300.webp"},"full":{"file":"seo-Search-intent.webp","width":2400,"height":1200,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent.webp"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.freelance.ro\/blog\/wp-content\/uploads\/2025\/02\/seo-Search-intent.webp","_links":{"self":[{"href":"https:\/\/www.freelance.ro\/blog\/wp-json\/wp\/v2\/media\/2206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.freelance.ro\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.freelance.ro\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.freelance.ro\/blog\/wp-json\/wp\/v2\/users\/11"}]}}